{"id":65,"date":"2016-02-22T09:53:27","date_gmt":"2016-02-22T08:53:27","guid":{"rendered":"https:\/\/www.sapy-secours.fr\/?p=65"},"modified":"2022-03-07T10:37:27","modified_gmt":"2022-03-07T09:37:27","slug":"remerciements-salon-secours-expo-2016","status":"publish","type":"post","link":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/","title":{"rendered":"Remerciements Salon Secours Expo 2016"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Toute l\u2019\u00e9quipe de <strong>Sapy<\/strong> et <strong>Cardiosecours<\/strong> a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce fut pour nous l\u2019occasion de vous pr\u00e9senter notre gamme de produits et mat\u00e9riels de <strong>premiers soins<\/strong> et premiers secours. Ce salon nous a permis de nous retrouver au milieu des diff\u00e9rents acteurs du secours et des soins d&rsquo;urgence et ainsi d\u00e9montrer notre savoir-faire dans ce domaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons \u00e9galement pu rencontrer plusieurs de nos fid\u00e8les fournisseurs sur le salon et aussi de prendre contact avec d&rsquo;autres potentiels fabricants pour des projets \u00e0 venir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci pour votre visite et rendez-vous au prochain salon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris. Ce fut pour nous l\u2019occasion de vous pr\u00e9senter notre gamme de produits et mat\u00e9riels de premiers soins et premiers secours. Ce salon nous a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":66,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Remerciements Salon Secours Expo 2016 - Blog Sapy Secours<\/title>\n<meta name=\"description\" content=\"Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remerciements Salon Secours Expo 2016 - Blog Sapy Secours\" \/>\n<meta property=\"og:description\" content=\"Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Sapy Secours\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-22T08:53:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-07T09:37:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sapy-secours.fr\/blog\/wp-content\/uploads\/2022\/03\/13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"altais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"altais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/\"},\"author\":{\"name\":\"altais\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/#\\\/schema\\\/person\\\/96d029e78e6f9ace7a8dd49cbd6bdc5c\"},\"headline\":\"Remerciements Salon Secours Expo 2016\",\"datePublished\":\"2016-02-22T08:53:27+00:00\",\"dateModified\":\"2022-03-07T09:37:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/\"},\"wordCount\":121,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/13.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/\",\"url\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/\",\"name\":\"Remerciements Salon Secours Expo 2016 - Blog Sapy Secours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/13.jpg\",\"datePublished\":\"2016-02-22T08:53:27+00:00\",\"dateModified\":\"2022-03-07T09:37:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/#\\\/schema\\\/person\\\/96d029e78e6f9ace7a8dd49cbd6bdc5c\"},\"description\":\"Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/13.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/13.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/2016\\\/02\\\/22\\\/remerciements-salon-secours-expo-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Remerciements Salon Secours Expo 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/\",\"name\":\"Blog Sapy Secours\",\"description\":\"Actualit\u00e9s sur la d\u00e9fibrillation avec SapySecours\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/#\\\/schema\\\/person\\\/96d029e78e6f9ace7a8dd49cbd6bdc5c\",\"name\":\"altais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06f73fc34f02f2277fd0f7937bbe8b19a57f78722d41ee50ea7a9429fa2c02e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06f73fc34f02f2277fd0f7937bbe8b19a57f78722d41ee50ea7a9429fa2c02e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06f73fc34f02f2277fd0f7937bbe8b19a57f78722d41ee50ea7a9429fa2c02e9?s=96&d=mm&r=g\",\"caption\":\"altais\"},\"sameAs\":[\"https:\\\/\\\/preprod.sapysecours.altais.fr\\\/blog\"],\"url\":\"https:\\\/\\\/www.sapy-secours.fr\\\/blog\\\/author\\\/altais\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remerciements Salon Secours Expo 2016 - Blog Sapy Secours","description":"Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/","og_locale":"fr_FR","og_type":"article","og_title":"Remerciements Salon Secours Expo 2016 - Blog Sapy Secours","og_description":"Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.","og_url":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/","og_site_name":"Blog Sapy Secours","article_published_time":"2016-02-22T08:53:27+00:00","article_modified_time":"2022-03-07T09:37:27+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.sapy-secours.fr\/blog\/wp-content\/uploads\/2022\/03\/13.jpg","type":"image\/jpeg"}],"author":"altais","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"altais","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#article","isPartOf":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/"},"author":{"name":"altais","@id":"https:\/\/www.sapy-secours.fr\/blog\/#\/schema\/person\/96d029e78e6f9ace7a8dd49cbd6bdc5c"},"headline":"Remerciements Salon Secours Expo 2016","datePublished":"2016-02-22T08:53:27+00:00","dateModified":"2022-03-07T09:37:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/"},"wordCount":121,"commentCount":0,"image":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sapy-secours.fr\/blog\/wp-content\/uploads\/2022\/03\/13.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/","url":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/","name":"Remerciements Salon Secours Expo 2016 - Blog Sapy Secours","isPartOf":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sapy-secours.fr\/blog\/wp-content\/uploads\/2022\/03\/13.jpg","datePublished":"2016-02-22T08:53:27+00:00","dateModified":"2022-03-07T09:37:27+00:00","author":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/#\/schema\/person\/96d029e78e6f9ace7a8dd49cbd6bdc5c"},"description":"Toute l\u2019\u00e9quipe de Sapy et Cardiosecours a \u00e9t\u00e9 tr\u00e8s heureuse de vous accueillir les 2, 3 et 4 f\u00e9vrier lors du salon Secours Expo \u00e0 la Porte de Versailles \u00e0 Paris.","breadcrumb":{"@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#primaryimage","url":"https:\/\/www.sapy-secours.fr\/blog\/wp-content\/uploads\/2022\/03\/13.jpg","contentUrl":"https:\/\/www.sapy-secours.fr\/blog\/wp-content\/uploads\/2022\/03\/13.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.sapy-secours.fr\/blog\/2016\/02\/22\/remerciements-salon-secours-expo-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sapy-secours.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Remerciements Salon Secours Expo 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.sapy-secours.fr\/blog\/#website","url":"https:\/\/www.sapy-secours.fr\/blog\/","name":"Blog Sapy Secours","description":"Actualit\u00e9s sur la d\u00e9fibrillation avec SapySecours","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sapy-secours.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sapy-secours.fr\/blog\/#\/schema\/person\/96d029e78e6f9ace7a8dd49cbd6bdc5c","name":"altais","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/06f73fc34f02f2277fd0f7937bbe8b19a57f78722d41ee50ea7a9429fa2c02e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06f73fc34f02f2277fd0f7937bbe8b19a57f78722d41ee50ea7a9429fa2c02e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06f73fc34f02f2277fd0f7937bbe8b19a57f78722d41ee50ea7a9429fa2c02e9?s=96&d=mm&r=g","caption":"altais"},"sameAs":["https:\/\/preprod.sapysecours.altais.fr\/blog"],"url":"https:\/\/www.sapy-secours.fr\/blog\/author\/altais\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":1,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":67,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/posts\/65\/revisions\/67"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/media\/66"}],"wp:attachment":[{"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sapy-secours.fr\/blog\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}